{"id":182,"count":5,"description":"","link":"https:\/\/tiger-recruitment.com\/eur\/job-seekers-eur\/","name":"Jobseekers","slug":"job-seekers-eur","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jobseekers Archives - Tiger Recruitment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tiger-recruitment.com\/eur\/job-seekers-eur\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jobseekers Archives - Tiger Recruitment\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tiger-recruitment.com\/eur\/job-seekers-eur\/\" \/>\n<meta property=\"og:site_name\" content=\"Tiger Recruitment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@tigerrecruit\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jobseekers Archives - Tiger Recruitment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tiger-recruitment.com\/eur\/job-seekers-eur\/","og_locale":"en_US","og_type":"article","og_title":"Jobseekers Archives - Tiger Recruitment","og_url":"https:\/\/tiger-recruitment.com\/eur\/job-seekers-eur\/","og_site_name":"Tiger Recruitment","twitter_card":"summary_large_image","twitter_site":"@tigerrecruit","schema":{"@context":"https:\/\/schema.org","@graph":[]}},"_links":{"self":[{"href":"https:\/\/tiger-recruitment.com\/eur\/wp-json\/wp\/v2\/categories\/182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiger-recruitment.com\/eur\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/tiger-recruitment.com\/eur\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/tiger-recruitment.com\/eur\/wp-json\/wp\/v2\/posts?categories=182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}