{"id":1207741,"date":"2025-02-07T15:59:45","date_gmt":"2025-02-07T15:59:45","guid":{"rendered":"https:\/\/tiger-recruitment.com\/?page_id=1207741"},"modified":"2025-02-10T15:26:10","modified_gmt":"2025-02-10T15:26:10","slug":"promotion-terms-and-conditions","status":"publish","type":"page","link":"https:\/\/tiger-recruitment.com\/ae\/promotion-terms-and-conditions\/","title":{"rendered":"Promotion T&#038;Cs"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":57471,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1207741","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Promotion T&amp;Cs - Tiger Recruitment<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tiger-recruitment.com\/ae\/promotion-terms-and-conditions\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Promotion T&amp;Cs - Tiger Recruitment\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tiger-recruitment.com\/ae\/promotion-terms-and-conditions\/\" \/>\n<meta property=\"og:site_name\" content=\"Tiger Recruitment\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tigerrecruitment.ltd\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-10T15:26:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@tigerrecruit\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Promotion T&Cs - Tiger Recruitment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tiger-recruitment.com\/ae\/promotion-terms-and-conditions\/","og_locale":"en_US","og_type":"article","og_title":"Promotion T&Cs - Tiger Recruitment","og_url":"https:\/\/tiger-recruitment.com\/ae\/promotion-terms-and-conditions\/","og_site_name":"Tiger Recruitment","article_publisher":"https:\/\/www.facebook.com\/tigerrecruitment.ltd\/","article_modified_time":"2025-02-10T15:26:10+00:00","twitter_card":"summary_large_image","twitter_site":"@tigerrecruit","schema":{"@context":"https:\/\/schema.org","@graph":[]}},"_links":{"self":[{"href":"https:\/\/tiger-recruitment.com\/ae\/wp-json\/wp\/v2\/pages\/1207741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tiger-recruitment.com\/ae\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tiger-recruitment.com\/ae\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tiger-recruitment.com\/ae\/wp-json\/wp\/v2\/users\/57471"}],"replies":[{"embeddable":true,"href":"https:\/\/tiger-recruitment.com\/ae\/wp-json\/wp\/v2\/comments?post=1207741"}],"version-history":[{"count":0,"href":"https:\/\/tiger-recruitment.com\/ae\/wp-json\/wp\/v2\/pages\/1207741\/revisions"}],"wp:attachment":[{"href":"https:\/\/tiger-recruitment.com\/ae\/wp-json\/wp\/v2\/media?parent=1207741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}